{"id":34968,"date":"2026-06-30T09:05:14","date_gmt":"2026-06-30T07:05:14","guid":{"rendered":"https:\/\/kulturquartier.leoben.at\/?post_type=events&#038;p=34968"},"modified":"2026-07-21T14:26:46","modified_gmt":"2026-07-21T12:26:46","slug":"erzaehltheater-drache-kokosnuss","status":"publish","type":"events","link":"https:\/\/kulturquartier.leoben.at\/en\/events\/erzaehltheater-drache-kokosnuss\/","title":{"rendered":"Erz\u00e4hltheater: Der kleine Drache Kokosnuss"},"content":{"rendered":"","protected":false},"author":26,"featured_media":0,"template":"","facilities":[],"holiday_themes":[],"event_towns":[],"event_locations":[],"class_list":["post-34968","events","type-events","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erz\u00e4hltheater: Der kleine Drache Kokosnuss - Kulturquartier<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kulturquartier.leoben.at\/en\/events\/erzaehltheater-drache-kokosnuss\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erz\u00e4hltheater: Der kleine Drache Kokosnuss - Kulturquartier\" \/>\n<meta property=\"og:description\" content=\"Willkommen im KulturQuartier Leoben\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kulturquartier.leoben.at\/en\/events\/erzaehltheater-drache-kokosnuss\/\" \/>\n<meta property=\"og:site_name\" content=\"Kulturquartier\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-21T12:26:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kulturquartier.leoben.at\/wp-content\/uploads\/sites\/4\/2026\/07\/Der-kleine-Drache-Kokosnuss-c-cbj-Kinder-und-Jugendbuchverlag.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kulturquartier.leoben.at\\\/en\\\/events\\\/erzaehltheater-drache-kokosnuss\\\/\",\"url\":\"https:\\\/\\\/kulturquartier.leoben.at\\\/en\\\/events\\\/erzaehltheater-drache-kokosnuss\\\/\",\"name\":\"Erz\u00e4hltheater: Der kleine Drache Kokosnuss - Kulturquartier\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kulturquartier.leoben.at\\\/en\\\/#website\"},\"datePublished\":\"2026-06-30T07:05:14+00:00\",\"dateModified\":\"2026-07-21T12:26:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kulturquartier.leoben.at\\\/en\\\/events\\\/erzaehltheater-drache-kokosnuss\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kulturquartier.leoben.at\\\/en\\\/events\\\/erzaehltheater-drache-kokosnuss\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kulturquartier.leoben.at\\\/en\\\/events\\\/erzaehltheater-drache-kokosnuss\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/kulturquartier.leoben.at\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erz\u00e4hltheater: Der kleine Drache Kokosnuss\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kulturquartier.leoben.at\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/kulturquartier.leoben.at\\\/en\\\/\",\"name\":\"Kulturquartier\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kulturquartier.leoben.at\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erz\u00e4hltheater: Der kleine Drache Kokosnuss - Kulturquartier","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kulturquartier.leoben.at\/en\/events\/erzaehltheater-drache-kokosnuss\/","og_locale":"en_US","og_type":"article","og_title":"Erz\u00e4hltheater: Der kleine Drache Kokosnuss - Kulturquartier","og_description":"Willkommen im KulturQuartier Leoben","og_url":"https:\/\/kulturquartier.leoben.at\/en\/events\/erzaehltheater-drache-kokosnuss\/","og_site_name":"Kulturquartier","article_modified_time":"2026-07-21T12:26:46+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/kulturquartier.leoben.at\/wp-content\/uploads\/sites\/4\/2026\/07\/Der-kleine-Drache-Kokosnuss-c-cbj-Kinder-und-Jugendbuchverlag.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kulturquartier.leoben.at\/en\/events\/erzaehltheater-drache-kokosnuss\/","url":"https:\/\/kulturquartier.leoben.at\/en\/events\/erzaehltheater-drache-kokosnuss\/","name":"Erz\u00e4hltheater: Der kleine Drache Kokosnuss - Kulturquartier","isPartOf":{"@id":"https:\/\/kulturquartier.leoben.at\/en\/#website"},"datePublished":"2026-06-30T07:05:14+00:00","dateModified":"2026-07-21T12:26:46+00:00","breadcrumb":{"@id":"https:\/\/kulturquartier.leoben.at\/en\/events\/erzaehltheater-drache-kokosnuss\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kulturquartier.leoben.at\/en\/events\/erzaehltheater-drache-kokosnuss\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kulturquartier.leoben.at\/en\/events\/erzaehltheater-drache-kokosnuss\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/kulturquartier.leoben.at\/en\/"},{"@type":"ListItem","position":2,"name":"Erz\u00e4hltheater: Der kleine Drache Kokosnuss"}]},{"@type":"WebSite","@id":"https:\/\/kulturquartier.leoben.at\/en\/#website","url":"https:\/\/kulturquartier.leoben.at\/en\/","name":"Kulturquartier","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kulturquartier.leoben.at\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/kulturquartier.leoben.at\/en\/wp-json\/wp\/v2\/events\/34968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kulturquartier.leoben.at\/en\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/kulturquartier.leoben.at\/en\/wp-json\/wp\/v2\/types\/events"}],"author":[{"embeddable":true,"href":"https:\/\/kulturquartier.leoben.at\/en\/wp-json\/wp\/v2\/users\/26"}],"version-history":[{"count":1,"href":"https:\/\/kulturquartier.leoben.at\/en\/wp-json\/wp\/v2\/events\/34968\/revisions"}],"predecessor-version":[{"id":35131,"href":"https:\/\/kulturquartier.leoben.at\/en\/wp-json\/wp\/v2\/events\/34968\/revisions\/35131"}],"wp:attachment":[{"href":"https:\/\/kulturquartier.leoben.at\/en\/wp-json\/wp\/v2\/media?parent=34968"}],"wp:term":[{"taxonomy":"facilities","embeddable":true,"href":"https:\/\/kulturquartier.leoben.at\/en\/wp-json\/wp\/v2\/facilities?post=34968"},{"taxonomy":"holiday_themes","embeddable":true,"href":"https:\/\/kulturquartier.leoben.at\/en\/wp-json\/wp\/v2\/holiday_themes?post=34968"},{"taxonomy":"event_towns","embeddable":true,"href":"https:\/\/kulturquartier.leoben.at\/en\/wp-json\/wp\/v2\/event_towns?post=34968"},{"taxonomy":"event_locations","embeddable":true,"href":"https:\/\/kulturquartier.leoben.at\/en\/wp-json\/wp\/v2\/event_locations?post=34968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}